{"id":11630,"date":"2025-08-13T13:25:23","date_gmt":"2025-08-13T06:25:23","guid":{"rendered":"https:\/\/www.serenatahotels.com\/the-art-of-slow-travel-why-the-green-season-is-for-dreamers\/"},"modified":"2025-08-13T13:30:49","modified_gmt":"2025-08-13T06:30:49","slug":"the-art-of-slow-travel-why-the-green-season-is-for-dreamers","status":"publish","type":"post","link":"https:\/\/www.serenatahotels.com\/th\/the-art-of-slow-travel-why-the-green-season-is-for-dreamers\/","title":{"rendered":"\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e49\u0e32 \u2013 \u0e17\u0e33\u0e44\u0e21\u0e24\u0e14\u0e39\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e16\u0e36\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e1d\u0e31\u0e19"},"content":{"rendered":"\n<p>\u0e43\u0e19\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e23\u0e47\u0e27 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e49\u0e32\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2b\u0e22\u0e38\u0e14\u0e2b\u0e32\u0e22\u0e43\u0e08 \u0e25\u0e30\u0e40\u0e25\u0e35\u0e22\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e24\u0e14\u0e39\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e43\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30 <strong>\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e0b\u0e40\u0e23\u0e19\u0e32\u0e15\u0e49\u0e32<\/strong> \u0e21\u0e35\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e40\u0e23\u0e48\u0e07\u0e23\u0e35\u0e1a \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e34\u0e21\u0e19\u0e49\u0e33\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n\n\n\n<p><strong><em>\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e20\u0e32\u0e1e: \u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01\u0e40\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e1a\u0e19\u0e40\u0e1b\u0e25\u0e0d\u0e27\u0e19\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33 \u0e1d\u0e19\u0e42\u0e1b\u0e23\u0e22\u0e40\u0e1a\u0e32 \u0e46 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07.<\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u0e40\u0e0a\u0e49\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e35\u0e1a<\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u0e15\u0e37\u0e48\u0e19\u0e02\u0e36\u0e49\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1d\u0e19 \u0e08\u0e34\u0e1a\u0e01\u0e32\u0e41\u0e1f\u0e21\u0e2d\u0e07\u0e2b\u0e21\u0e2d\u0e01\u0e04\u0e48\u0e2d\u0e22 \u0e46 \u0e25\u0e2d\u0e22\u0e02\u0e36\u0e49\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e20\u0e39\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e43\u0e19\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14<\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19\u0e40\u0e1c\u0e32 \u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e0a\u0e21\u0e17\u0e38\u0e48\u0e07\u0e19\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e48\u0e07\u0e01\u0e34\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e27\u0e31\u0e19\u0e22\u0e32\u0e27 \u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e34\u0e27\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e32\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/strong> \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e2a\u0e42\u0e25\u0e27\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"https:\/\/www.serenatahotels.com\/th\/\"><strong>SERENATA Hotels &amp; Resorts<\/strong><\/a> \u0e41\u0e25\u0e49\u0e27\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e19\u0e32\u0e17\u0e35\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0440623525f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0440623525f\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"11080\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-1024x683.webp\" alt=\"\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\" class=\"wp-image-11080\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-1024x683.webp 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-300x200.webp 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-768x512.webp 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-600x400.webp 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-500x333.webp 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35-800x533.webp 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.2-\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e15\u0e48\u0e2d\u0e07-\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e34\u0e25\u0e4a\u0e2d\u0e01\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0440623605e&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0440623605e\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"11078\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-1024x683.webp\" alt=\"\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\" class=\"wp-image-11078\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-1024x683.webp 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-300x200.webp 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-768x512.webp 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-600x400.webp 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-500x333.webp 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35-800x533.webp 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.3-\u0e17\u0e38\u0e48\u0e07\u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04406236ef5&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04406236ef5\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"11076\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-1024x683.webp\" alt=\"10 \u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22 \u0e46\" class=\"wp-image-11076\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-1024x683.webp 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-300x200.webp 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-768x512.webp 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-600x400.webp 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-500x333.webp 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46-800x533.webp 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/02\/17.1-10-\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e27\u0e43\u0e01\u0e25\u0e49\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e27\u0e22-\u0e46.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04406237bba&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04406237bba\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"956\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"10782\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/Le-Chame-Sukhothai-Medium.jpeg\" alt=\"\" class=\"wp-image-10782\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/Le-Chame-Sukhothai-Medium.jpeg 956w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/Le-Chame-Sukhothai-Medium-300x241.jpeg 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/Le-Chame-Sukhothai-Medium-768x617.jpeg 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/Le-Chame-Sukhothai-Medium-500x402.jpeg 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/Le-Chame-Sukhothai-Medium-800x643.jpeg 800w\" sizes=\"auto, (max-width: 956px) 100vw, 956px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a044062388fd&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a044062388fd\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"10774\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-1024x683.jpeg\" alt=\"\" class=\"wp-image-10774\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-1024x683.jpeg 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-300x200.jpeg 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-768x512.jpeg 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-500x333.jpeg 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-800x533.jpeg 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium-600x400.jpeg 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2025\/01\/bjgvH9aP-Medium.jpeg 1152w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04406239701&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04406239701\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"619\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"10697\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/12\/rhh-zen-plus-150722-04-1024x619-1.webp\" alt=\"\" class=\"wp-image-10697\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/12\/rhh-zen-plus-150722-04-1024x619-1.webp 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/12\/rhh-zen-plus-150722-04-1024x619-1-300x181.webp 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/12\/rhh-zen-plus-150722-04-1024x619-1-768x464.webp 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/12\/rhh-zen-plus-150722-04-1024x619-1-500x302.webp 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/12\/rhh-zen-plus-150722-04-1024x619-1-800x484.webp 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0440623a411&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0440623a411\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"10201\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-1024x683.webp\" alt=\"\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c\" class=\"wp-image-10201\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-1024x683.webp 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-300x200.webp 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-768x512.webp 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-500x333.webp 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-800x533.webp 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c-600x400.webp 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/09\/17.3-\u0e27\u0e31\u0e14\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0440623b0d2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0440623b0d2\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"10113\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-1024x683.jpg\" alt=\"\u0e17\u0e23\u0e35\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2b\u0e23\u0e39 \u0e40\u0e01\u0e32\u0e30\u0e22\u0e32\u0e27 \" class=\"wp-image-10113\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-1024x683.jpg 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-300x200.jpg 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-768x512.jpg 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-1536x1024.jpg 1536w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-500x333.jpg 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-800x533.jpg 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-1280x853.jpg 1280w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1-600x400.jpg 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2021\/04\/TreeHouse-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0440623bc8d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0440623bc8d\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"10015\" src=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-1024x683.webp\" alt=\"\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e\" class=\"wp-image-10015\" title=\"\" srcset=\"https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-1024x683.webp 1024w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-300x200.webp 300w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-768x512.webp 768w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-500x333.webp 500w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-800x533.webp 800w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e-600x400.webp 600w, https:\/\/www.serenatahotels.com\/wp-content\/uploads\/2024\/08\/18.5-\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e17\u0e1e.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.serenatahotels.com\/th\/hotels-resorts\/\">\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e43\u0e19\u0e1d\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e19\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e23\u0e47\u0e27 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e49\u0e32\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2b\u0e22\u0e38\u0e14\u0e2b\u0e32\u0e22\u0e43\u0e08 \u0e25\u0e30\u0e40\u0e25\u0e35\u0e22\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e24\u0e14\u0e39\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e43\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e0b\u0e40\u0e23\u0e19\u0e32\u0e15\u0e49\u0e32 \u0e21\u0e35\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e40\u0e23\u0e48\u0e07\u0e23\u0e35\u0e1a \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e34\u0e21\u0e19\u0e49\u0e33\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n","protected":false},"author":10,"featured_media":9618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","footnotes":""},"categories":[333],"tags":[],"class_list":["post-11630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-serenata-group-th"],"meta_box":{"tag_line":false,"collection":false,"destination":false,"order":false,"orderby":false,"height":false,"cover_type":false,"slide_items":[],"image":false,"video_self_hosted":[],"type":false,"post":false,"title":false,"link_url":false,"link_target":false,"link_label":false,"show_link":false,"blog_to_property_to":[]},"_links":{"self":[{"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/posts\/11630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/comments?post=11630"}],"version-history":[{"count":2,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/posts\/11630\/revisions"}],"predecessor-version":[{"id":11643,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/posts\/11630\/revisions\/11643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/media\/9618"}],"wp:attachment":[{"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/media?parent=11630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/categories?post=11630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.serenatahotels.com\/th\/wp-json\/wp\/v2\/tags?post=11630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}